{"id":4343,"date":"2024-04-09T15:46:45","date_gmt":"2024-04-09T13:46:45","guid":{"rendered":"https:\/\/www.sportplussrl.it\/cassano-dadda\/?p=4343"},"modified":"2024-04-09T15:46:45","modified_gmt":"2024-04-09T13:46:45","slug":"la-sfacchinata-inclusiva","status":"publish","type":"post","link":"https:\/\/sportplussrl.it\/cassano-dadda\/la-sfacchinata-inclusiva\/","title":{"rendered":"La Sfacchinata Inclusiva"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Sezione&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/sportplussrl.it\/cassano-dadda\/wp-content\/uploads\/sites\/7\/2024\/04\/header-sito-sfacchinata-inclusiva-1536&#215;469-1.jpg&#8221; title_text=&#8221;header-sito-sfacchinata-inclusiva-1536&#215;469-1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Testo&#8221; _builder_version=&#8221;4.18.0&#8243; link_font=&#8221;||||on|||#0c71c3|&#8221; link_text_color=&#8221;#0c71c3&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_font_size=&#8221;45px&#8221; header_4_text_color=&#8221;#004653&#8243; header_4_font_size=&#8221;20px&#8221; header_5_font=&#8221;Montserrat||||||||&#8221; header_5_text_color=&#8221;#004653&#8243; header_5_font_size=&#8221;20px&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;||0px|||&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; header_font_size__hover_enabled=&#8221;off|desktop&#8221;]<\/p>\n<div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p style=\"text-align: center\">COMUNICATO STAMPA<\/p>\n<p style=\"text-align: center\">\u201cIn Sport e Sport Active: La Sfacchinata Inclusiva ha fatto nuotare tutti\u201d<\/p>\n<p style=\"text-align: center\"><i>Biella \u2013 Cassano d\u2019Adda \u2013 Concorezzo \u2013 Cormano e Segrate, 9 Aprile 2024 <\/i><\/p>\n<p style=\"text-align: center\">\u00c8 stata una grande giornata di\u00a0sport, divertimento e inclusione\u00a0quella di Domenica\u00a07 Aprile 2024\u00a0presso i\u00a0Centri Sportivi Natatori\u00a0di\u00a0Biella, Cassano d\u2019Adda, Concorezzo, Cormano\u00a0e\u00a0Segrate\u00a0dove \u2013 in contemporanea \u2013 \u00e8 andata in scena la\u00a01a\u00a0edizione\u00a0de\u00a0\u201cLA SFACCHINATA INCLUSIVA\u201d: 3 ore di\u00a0nuoto non stop, aperte a tutti, senza distinzione di et\u00e0, sesso, preparazione atletica\u00a0e\u00a0condizione fisica.<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/sportplussrl.it\/cassano-dadda\/wp-content\/uploads\/sites\/7\/2024\/04\/Schermata-2024-04-09-alle-09.57.46-1.png&#8221; title_text=&#8221;Schermata-2024-04-09-alle-09.57.46&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Testo&#8221; _builder_version=&#8221;4.18.0&#8243; link_font=&#8221;||||on|||#0c71c3|&#8221; link_text_color=&#8221;#0c71c3&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_font_size=&#8221;45px&#8221; header_4_text_color=&#8221;#004653&#8243; header_4_font_size=&#8221;20px&#8221; header_5_font=&#8221;Montserrat||||||||&#8221; header_5_text_color=&#8221;#004653&#8243; header_5_font_size=&#8221;20px&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;||0px|||&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; header_font_size__hover_enabled=&#8221;off|desktop&#8221;]<\/p>\n<div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\">La manifestazione \u00e8 stata <strong>organizzata da IN SPORT <\/strong>e<strong> SPORT ACTIVE<\/strong>, <strong>Societ\u00e0 Sportive Dilettantistiche<\/strong> riconosciute come punto di riferimento del settore (oltre 20 centri sportivi in gestione in 3 Regioni), con l\u2019obiettivo di mostrare al pubblico la splendida realt\u00e0 dello sport in acqua dove uomini, donne, adulti, bambini e persone con disabilit\u00e0 <strong>possono gareggiare insieme<\/strong>. Un evento a scopo ludico (non agonistico) di nuoto a staffetta, senza vincoli nella formazione delle squadre, con il premio puramente \u201csimbolico\u201d alla compagine che ha completato il maggior numero di vasche al termine delle 3 ore.<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/sportplussrl.it\/cassano-dadda\/wp-content\/uploads\/sites\/7\/2024\/04\/LaSfacchinataInclusiva-5-1.jpg&#8221; title_text=&#8221;LaSfacchinataInclusiva-5&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;37%&#8221; max_width=&#8221;37%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Testo&#8221; _builder_version=&#8221;4.18.0&#8243; link_font=&#8221;||||on|||#0c71c3|&#8221; link_text_color=&#8221;#0c71c3&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_font_size=&#8221;45px&#8221; header_4_text_color=&#8221;#004653&#8243; header_4_font_size=&#8221;20px&#8221; header_5_font=&#8221;Montserrat||||||||&#8221; header_5_text_color=&#8221;#004653&#8243; header_5_font_size=&#8221;20px&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;||0px|||&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; header_font_size__hover_enabled=&#8221;off|desktop&#8221;]<\/p>\n<div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p>&nbsp;<\/p>\n<p>Il progetto de \u201cLA SFACCHINATA INCLUSIVA\u201d \u00e8 stato seguito con sincero entusiasmo dalle <strong>Amministrazioni Comunali <\/strong>(in rigoroso ordine alfabetico) di Biella, Cassano d\u2019Adda, Concorezzo, Cormano e Segrate che hanno concesso il loro <strong>Patrocinio<\/strong>, cos\u00ec come l\u2019Ente di Promozione Sportiva <strong>CNS Libertas<\/strong> ed il <strong>CONI Regionale Lombardia<\/strong> che, nella figura del <strong>Presidente Marco Riva<\/strong>, ha espresso grande apprezzamento per l\u2019iniziativa.<\/p>\n<p>&nbsp;<\/p>\n<p>In contemporanea presso <u>5 impianti<\/u>, in <u>5 Comuni<\/u>, in <u>3 Province<\/u> (Biella, Milano e Monza Brianza), in <u>2 Regioni<\/u> (Lombardia e Piemonte), <strong>30 squadre<\/strong> per <strong>212 partecipanti<\/strong> complessivi (dai pi\u00f9 giovani di 6 anni ai pi\u00f9 \u201cesperti\u201d di quasi 70 anni) hanno completato <strong>8.083 vasche<\/strong>, per un totale di <strong>202.075 metri<\/strong> totali percorsi (poco meno della distanza tra Milano e Bologna) dai nuotatori in gara.<\/p>\n<p style=\"text-align: center\">\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/sportplussrl.it\/cassano-dadda\/wp-content\/uploads\/sites\/7\/2024\/04\/LaSfacchinataInclusiva-1-1.jpg&#8221; title_text=&#8221;LaSfacchinataInclusiva-1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Testo&#8221; _builder_version=&#8221;4.18.0&#8243; link_font=&#8221;||||on|||#0c71c3|&#8221; link_text_color=&#8221;#0c71c3&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_font_size=&#8221;45px&#8221; header_4_text_color=&#8221;#004653&#8243; header_4_font_size=&#8221;20px&#8221; header_5_font=&#8221;Montserrat||||||||&#8221; header_5_text_color=&#8221;#004653&#8243; header_5_font_size=&#8221;20px&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;||0px|||&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; header_font_size__hover_enabled=&#8221;off|desktop&#8221;]<\/p>\n<div class=\"et_pb_module et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p style=\"text-align: center\">Grande e propositiva la partecipazione del mondo associativo territoriale: L&#8217;Arcobaleno Societ\u00e0 Cooperativa Sociale Onlus, Il Quadrifoglio Societ\u00e0 Cooperativa Sociale, Granda Waterpolo Ability ASD, OSHa Como ASD, SpecialMente Ivrea e Lambro Societ\u00e0 Cooperativa Sociale Onlus, tutte giunte a testimoniare come lo sport sia un potentissimo strumento di inclusivit\u00e0.<\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\">Un caloroso ringraziamento ai <strong>Partner<\/strong> che hanno sostenuto la manifestazione:<\/p>\n<ul style=\"text-align: center\">\n<li><strong>Acquatec srl<\/strong> \u2013 leader nel settore dell\u2019idraulica, riscaldamento e condizionamento <a href=\"https:\/\/www.acquatec.com\/\">https:\/\/www.acquatec.com\/<\/a><\/li>\n<li><strong>Farmacia San Paolo di Biella<\/strong> \u2013 <a href=\"https:\/\/www.farmasanpaolo.it\/\">https:\/\/www.farmasanpaolo.it\/<\/a><\/li>\n<li><strong>Natural Boom<\/strong> \u2013 il primo Mental Drink al mondo \u2013 <a href=\"https:\/\/naturalboom.it\/\">https:\/\/naturalboom.it\/<\/a><\/li>\n<\/ul>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center\">Un grande plauso finale ai Direttori ed a tutti gli Staff dei Centri IN SPORT (Biella, Cassano d\u2019Adda, Concorezzo e Segrate) e SPORT ACTIVE (Cormano) che hanno creduto fortemente nell\u2019evento lavorando alacremente alla sua organizzazione.<\/p>\n<p style=\"text-align: center\">\u201cLa Sfacchinata Inclusiva\u201d \u2013 nata da un\u2019idea dell\u2019Avv. Gianluca Mura \u2013 rientra nel pacchetto di attivit\u00e0 di IN SPORT e SPORT ACTIVE (tra cui anche il Progetto MOVEMENT <a href=\"https:\/\/www.sportplussrl.it\/progetto-movement\/\">https:\/\/www.sportplussrl.it\/progetto-movement\/<\/a>) volte a sensibilizzare le persone sull\u2019importanza dello sport come strumento di prevenzione e come elemento essenziale per una vita sana.<\/p>\n<p style=\"text-align: center\">Appuntamento al 2025!<\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n<h6 style=\"text-align: center\"><em>COMUNICATI TESTUALI ALLEGATI ALLA PRESENTE E-MAIL, SI DICHIARANO LIBERI DA DIRITTI E LIBERAMENTE PUBBLICABILI E AD USO GRATUITO PER IL RICEVENTE. IL <\/em><em>MITTENTE NON SI ASSUME ALCUNA RESPONSABILIT\u00c0 SULLA MESSA IN PUBBLICAZIONE DELLE STESSE SUL SITO O GIORNALI (ONLINE O CARTACEI) DEL RICEVENTE, SE NON PREVENTIVAMENTE CONCORDATE CON IL MITTENTE. IL MITTENTE CONCEDE IL DIRITTO AL RICEVENTE DI POTER RIADATTARE TESTO, IN BASE ALLE ESIGENZE EDITORIALI DEL RICEVENTE CHE SI PREOCCUPER\u00c0 DI NON MODIFICARNE IL SENSO E IL PRINCIPIO DELLE INFORAZIONI CONTENUTE. IL MITTENTE DICHIARA INOLTRE CHE MAGGIORENNI O EVENTUALI MINORI PRESENTI NELLE IMMAGINI ABBIANO RILASCIATO AL MITTENTE STESSO COMPROVATA LIBERATORIA PER IL LIBERO UTILIZZO DELLE IMMAGINI PERSONALI E, SPECIFICATAMENTE PER I MINORI, CHE SI SIA\u00a0ALTRES\u00cc ACCERTATA L&#8217;AUTORIZZAZIONE FIRMATA DA GENITORI O DA CHI NE ESERCITA PATRIA POTEST\u00c0. IL MEDESIMO ATTO VALE ANCHE PER GLI EVENTUALI LINK VIDEO DA YOUTUBE PER CONDIVISIONE SUI CANALI MEDIA DEL RICEVENTE.<\/em><\/h6>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMUNICATO STAMPA \u201cIn Sport e Sport Active: La Sfacchinata Inclusiva ha fatto nuotare tutti\u201d Biella \u2013 Cassano d\u2019Adda \u2013 Concorezzo \u2013 Cormano e Segrate, 9 Aprile 2024 \u00c8 stata una grande giornata di\u00a0sport, divertimento e inclusione\u00a0quella di Domenica\u00a07 Aprile 2024\u00a0presso i\u00a0Centri Sportivi Natatori\u00a0di\u00a0Biella, Cassano d\u2019Adda, Concorezzo, Cormano\u00a0e\u00a0Segrate\u00a0dove \u2013 in contemporanea \u2013 \u00e8 andata in scena [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[10,1],"tags":[],"class_list":["post-4343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-senza-categoria","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/posts\/4343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/comments?post=4343"}],"version-history":[{"count":0,"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/posts\/4343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/media\/4344"}],"wp:attachment":[{"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/media?parent=4343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/categories?post=4343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sportplussrl.it\/cassano-dadda\/wp-json\/wp\/v2\/tags?post=4343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}